{"id":92,"date":"2018-07-17T20:05:12","date_gmt":"2018-07-17T18:05:12","guid":{"rendered":"https:\/\/lapasiondeeducar.com\/?p=92"},"modified":"2023-01-30T17:59:27","modified_gmt":"2023-01-30T15:59:27","slug":"beneficios-oratoria","status":"publish","type":"post","link":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/educacion-global\/beneficios-oratoria\/","title":{"rendered":"Los ni\u00f1os que dominan la oratoria obtienen mejores notas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2018\/07\/oratoria.jpg\" alt=\"innovaci\u00f3n educativa \" width=\"800\" height=\"533\" class=\"alignnone wp-image-93 size-full\" title=\"innovaci\u00f3n educativa\" srcset=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2018\/07\/oratoria.jpg 800w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2018\/07\/oratoria-300x200.jpg 300w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2018\/07\/oratoria-768x512.jpg 768w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2018\/07\/oratoria-360x240.jpg 360w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-flat ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/educacion-global\/beneficios-oratoria\/#En_abril_de_2018_Ana_Torres_Menarguez_entrevistaba_en_el_diario_El_Pais_a_Neil_Mercer_Lancashire_1948_director_del_Centro_de_Oratoria_de_Cambridge_Mercer_ha_dedicado_su_carrera_a_estudiar_como_influye_la_forma_de_hablar_en_los_resultados_academicos_destacaba_los_beneficios_del_aprendizaje_de_la_oratoria_en_la_escuela_En_ella_incluso_se_atrevia_a_igualar_su_peso_academico_con_el_de_las_matematicas_Ademas_Mercer_subrayaba_la_necesidad_de_que_la_escuela_publica_inglesa_empiece_a_darse_cuenta_de_su_importancia_para_el_futuro_de_los_ninos\" >En abril de 2018, Ana Torres Men\u00e1rguez entrevistaba en el diario El Pa\u00eds a\u00a0Neil Mercer (Lancashire, 1948), director del Centro de Oratoria de Cambridge. Mercer ha dedicado su carrera a estudiar c\u00f3mo influye la forma de hablar en los resultados acad\u00e9micos, destacaba los beneficios del aprendizaje de la oratoria en la escuela. En ella, incluso se atrev\u00eda a igualar su peso acad\u00e9mico con el de las matem\u00e1ticas. Adem\u00e1s, Mercer subrayaba la necesidad de que la escuela p\u00fablica inglesa empiece a darse cuenta de su importancia para el futuro de los ni\u00f1os.<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/educacion-global\/beneficios-oratoria\/#El_Centro_de_Oratoria_de_Cambridge_esta_formado_por_ocho_expertos_investigadores_y_asesores_Su_funcion_es_mediante_la_investigacion_la_practica_y_su_influencia_en_las_politicas_publicas_ayudar_a_determinar_como_debe_ensenarse_la_oratoria_en_las_escuelas_De_hecho_actualmente_estan_asesorando_a_paises_como_Gales_y_Singapur\" >El Centro de Oratoria de Cambridge est\u00e1 formado por ocho expertos investigadores y asesores. Su funci\u00f3n es, mediante la investigaci\u00f3n, la pr\u00e1ctica y su influencia en las pol\u00edticas p\u00fablicas, ayudar\u00a0 a determinar c\u00f3mo debe ense\u00f1arse la oratoria en las escuelas. De hecho, actualmente est\u00e1n asesorando a pa\u00edses como Gales y Singapur.<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/educacion-global\/beneficios-oratoria\/#En_la_entrevista_Mercer_recuerda_que_los_ninos_desarrollan_su_comprension_del_mundo_sobre_todo_a_traves_de_la_interaccion_con_personas_dentro_de_su_entorno_%E2%80%9CNo_lo_hacen_como_individuos_aislados_sino_que_absorben_lo_que_ven_y_lo_que_oyen_de_los_demas%E2%80%9D\" >En la entrevista, Mercer recuerda que los ni\u00f1os desarrollan su comprensi\u00f3n del mundo sobre todo a trav\u00e9s de la interacci\u00f3n con personas dentro de su entorno. \u201cNo lo hacen como individuos aislados, sino que absorben lo que ven y lo que oyen de los dem\u00e1s.\u201d<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/educacion-global\/beneficios-oratoria\/#En_sus_investigaciones_su_equipo_ha_comprobado_como_la_adquisicion_del_lenguaje_y_la_exposicion_de_los_ninos_a_conversaciones_bien_construidas_durante_la_etapa_preescolar_esta_altamente_relacionado_con_los_resultados_academicos_posteriores_%E2%80%9CComo_profesor_nunca_debes_menospreciar_tu_influencia_en_los_ninos_La_forma_en_la_que_aprenden_a_hablar_depende_en_muchos_casos_de_la_manera_en_que_el_docente_se_dirige_a_ellos%E2%80%9D_Pero_la_clave_no_solo_se_encuentra_en_la_escuela_%E2%80%9CLos_ninos_que_de_forma_regular_se_ven_envueltos_en_dialogos_razonados_en_casa_son_mas_proclives_a_ser_mas_efectivos_en_su_expresion_oral_Es_en_la_familia_donde_aprenden_a_hablar_La_lengua_que_experimentan_sera_la_base_de_lo_que_son_capaces_de_expresar%E2%80%9D\" >En sus investigaciones su equipo ha comprobado c\u00f3mo la adquisici\u00f3n del lenguaje y la exposici\u00f3n de los ni\u00f1os a conversaciones bien construidas durante la etapa preescolar est\u00e1 altamente relacionado con los resultados acad\u00e9micos posteriores. \u201cComo profesor nunca debes menospreciar tu influencia en los ni\u00f1os. La forma en la que aprenden a hablar depende, en muchos casos, de la manera en que el docente se dirige a ellos.\u201d Pero la clave no s\u00f3lo se encuentra en la escuela: \u201cLos ni\u00f1os que de forma regular se ven envueltos en di\u00e1logos razonados en casa son m\u00e1s proclives a ser m\u00e1s efectivos en su expresi\u00f3n oral. Es en la familia donde aprenden a hablar.\u00a0 La lengua que experimentan ser\u00e1 la base de lo que son capaces de expresar.\u201d<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/educacion-global\/beneficios-oratoria\/#Uno_de_sus_estudios_Reasoning_as_a_scientist_ways_of_helping_children_to_use_language_to_learn_science_2003_ha_demostrado_que_los_ninos_que_dominan_la_oratoria_obtienen_mejores_notas_en_matematicas_y_ciencias_Y_es_que_el_discurso_es_crucial_en_las_ciencias_porque_ayuda_a_describir_observaciones_de_forma_clara_razonar_sobre_causas_y_efectos_plantear_preguntas_precisas_formular_hipotesis_analizar_de_forma_critica%E2%80%A6_Tambien_afirman_que_todas_esas_habilidades_brindaran_a_aquellos_que_las_aprendan_el_acceso_a_mejores_puestos_de_trabajo_porque_seran_capaces_de_negociar_sus_condiciones_laborales\" >Uno de sus estudios (Reasoning as a scientist: ways of helping children to use language to learn science, 2003), ha demostrado que los ni\u00f1os que dominan\u00a0la oratoria obtienen mejores notas en matem\u00e1ticas y ciencias. Y es que el discurso es crucial en las ciencias porque ayuda a describir observaciones de forma clara, razonar sobre causas y efectos, plantear preguntas precisas, formular hip\u00f3tesis, analizar de forma cr\u00edtica\u2026 Tambi\u00e9n afirman que todas esas habilidades brindar\u00e1n a aquellos que las aprendan el acceso a mejores puestos de trabajo porque ser\u00e1n capaces de negociar sus condiciones laborales.<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/educacion-global\/beneficios-oratoria\/#Su_proyecto_Exploratory_Talks_establece_unas_reglas_para_ensenar_a_los_profesores_a_promover_discusiones_en_el_aula_toda_la_informacion_relevante_se_comparte_todos_los_miembros_del_grupo_estan_invitados_a_contribuir_se_respetan_todas_las_ideas_todos_deben_exponer_de_forma_clara_sus_ideas_o_hay_que_llegar_a_un_acuerdo\" >Su proyecto Exploratory Talks establece unas reglas para ense\u00f1ar a los profesores a promover discusiones en el aula: toda la informaci\u00f3n relevante se comparte, todos los miembros del grupo est\u00e1n invitados a contribuir, se respetan todas las ideas, todos deben exponer de forma clara sus ideas, o hay que llegar a un acuerdo.<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/educacion-global\/beneficios-oratoria\/#De_esta_forma_los_ninos_con_mas_confianza_en_si_mismos_y_que_suelen_hablar_mas_tiempo_tienen_la_oportunidad_de_escuchar_otros_puntos_de_vista_Los_mas_parados_y_timidos_que_normalmente_se_quedan_callados_y_en_un_segundo_plano_sienten_que_su_contribucion_es_valorada_que_su_voz_vale_tanto_como_la_de_los_demas_Preguntar_al_resto_de_companeros_se_premia_por_parte_del_docente_y_a_la_larga_eso_conduce_a_un_mejor_entendimiento_de_la_postura_de_los_demas_a_una_mayor_empatia\" >De esta forma, los ni\u00f1os con m\u00e1s confianza en s\u00ed mismos y que suelen hablar m\u00e1s tiempo tienen la oportunidad de escuchar otros puntos de vista. Los m\u00e1s parados y t\u00edmidos, que normalmente se quedan callados y en un segundo plano, sienten que su contribuci\u00f3n es valorada, que su voz vale tanto como la de los dem\u00e1s. Preguntar al resto de compa\u00f1eros se premia por parte del docente y, a la larga, eso conduce a un mejor entendimiento de la postura de los dem\u00e1s, a una mayor empat\u00eda.<\/a><\/li><\/ul><\/nav><\/div>\n<h5><span class=\"ez-toc-section\" id=\"En_abril_de_2018_Ana_Torres_Menarguez_entrevistaba_en_el_diario_El_Pais_a_Neil_Mercer_Lancashire_1948_director_del_Centro_de_Oratoria_de_Cambridge_Mercer_ha_dedicado_su_carrera_a_estudiar_como_influye_la_forma_de_hablar_en_los_resultados_academicos_destacaba_los_beneficios_del_aprendizaje_de_la_oratoria_en_la_escuela_En_ella_incluso_se_atrevia_a_igualar_su_peso_academico_con_el_de_las_matematicas_Ademas_Mercer_subrayaba_la_necesidad_de_que_la_escuela_publica_inglesa_empiece_a_darse_cuenta_de_su_importancia_para_el_futuro_de_los_ninos\"><\/span>En abril de 2018, Ana Torres Men\u00e1rguez entrevistaba en el diario <a href=\"https:\/\/elpais.com\/economia\/2018\/03\/26\/actualidad\/1522064879_829810.html\" target=\"_blank\" rel=\"noopener noreferrer\">El Pa\u00eds a<\/a>\u00a0<strong>Neil Mercer (Lancashire, 1948), director del Centro de Oratoria de Cambridge. Mercer <\/strong>ha dedicado su carrera a estudiar c\u00f3mo influye la forma de hablar en los resultados acad\u00e9micos, destacaba los beneficios del aprendizaje de la oratoria en la escuela. En ella, <strong>incluso se atrev\u00eda a igualar su peso acad\u00e9mico con el de las matem\u00e1ticas. Adem\u00e1s, Mercer <\/strong>subrayaba la necesidad de que la escuela p\u00fablica inglesa empiece a darse cuenta de su importancia para el futuro de los ni\u00f1os.<span class=\"ez-toc-section-end\"><\/span><\/h5>\n<h6><span class=\"ez-toc-section\" id=\"El_Centro_de_Oratoria_de_Cambridge_esta_formado_por_ocho_expertos_investigadores_y_asesores_Su_funcion_es_mediante_la_investigacion_la_practica_y_su_influencia_en_las_politicas_publicas_ayudar_a_determinar_como_debe_ensenarse_la_oratoria_en_las_escuelas_De_hecho_actualmente_estan_asesorando_a_paises_como_Gales_y_Singapur\"><\/span>El <strong>Centro de Oratoria de Cambridge <\/strong>est\u00e1 formado por ocho expertos investigadores y asesores. Su funci\u00f3n es, mediante la investigaci\u00f3n, la pr\u00e1ctica y su influencia en las pol\u00edticas p\u00fablicas, ayudar\u00a0 a determinar c\u00f3mo debe ense\u00f1arse la oratoria en las escuelas. De hecho, actualmente est\u00e1n asesorando a pa\u00edses como Gales y Singapur.<span class=\"ez-toc-section-end\"><\/span><\/h6>\n<h6><span class=\"ez-toc-section\" id=\"En_la_entrevista_Mercer_recuerda_que_los_ninos_desarrollan_su_comprension_del_mundo_sobre_todo_a_traves_de_la_interaccion_con_personas_dentro_de_su_entorno_%E2%80%9CNo_lo_hacen_como_individuos_aislados_sino_que_absorben_lo_que_ven_y_lo_que_oyen_de_los_demas%E2%80%9D\"><\/span>En la entrevista, <strong>Mercer <\/strong>recuerda que los ni\u00f1os desarrollan su comprensi\u00f3n del mundo <a href=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/educacion-personalizada\/desarrollar-habilidades-sociales-ninos\/\">sobre todo a trav\u00e9s de la interacci\u00f3n con personas dentro de su entorno.<\/a> \u201cNo lo hacen como individuos aislados, sino que absorben lo que ven y lo que oyen de los dem\u00e1s.\u201d<span class=\"ez-toc-section-end\"><\/span><\/h6>\n<p><iframe loading=\"lazy\" title=\"&#039;Hablar en p\u00fablico&#039; - Proyecto educativo Gaztelueta\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/-E-4MVs6Pg0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h6><span class=\"ez-toc-section\" id=\"En_sus_investigaciones_su_equipo_ha_comprobado_como_la_adquisicion_del_lenguaje_y_la_exposicion_de_los_ninos_a_conversaciones_bien_construidas_durante_la_etapa_preescolar_esta_altamente_relacionado_con_los_resultados_academicos_posteriores_%E2%80%9CComo_profesor_nunca_debes_menospreciar_tu_influencia_en_los_ninos_La_forma_en_la_que_aprenden_a_hablar_depende_en_muchos_casos_de_la_manera_en_que_el_docente_se_dirige_a_ellos%E2%80%9D_Pero_la_clave_no_solo_se_encuentra_en_la_escuela_%E2%80%9CLos_ninos_que_de_forma_regular_se_ven_envueltos_en_dialogos_razonados_en_casa_son_mas_proclives_a_ser_mas_efectivos_en_su_expresion_oral_Es_en_la_familia_donde_aprenden_a_hablar_La_lengua_que_experimentan_sera_la_base_de_lo_que_son_capaces_de_expresar%E2%80%9D\"><\/span>En sus investigaciones su equipo ha comprobado c\u00f3mo<a href=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/educacion-trilingue\/trilinguismo-y-expresion-oral\/\"> la adquisici\u00f3n del lenguaje y la exposici\u00f3n de los ni\u00f1os a conversaciones bien construidas durante la etapa preescolar<\/a> est\u00e1 altamente relacionado con los resultados acad\u00e9micos posteriores. \u201cComo profesor nunca debes menospreciar tu influencia en los ni\u00f1os. La forma en la que aprenden a hablar depende, en muchos casos, de la manera en que el docente se dirige a ellos.\u201d Pero la clave no s\u00f3lo se encuentra en la escuela: \u201cLos ni\u00f1os que de forma regular se ven envueltos en di\u00e1logos razonados en casa son m\u00e1s proclives a ser m\u00e1s efectivos en su expresi\u00f3n oral. Es en la familia donde aprenden a hablar.\u00a0 La lengua que experimentan ser\u00e1 la base de lo que son capaces de expresar.\u201d<span class=\"ez-toc-section-end\"><\/span><\/h6>\n<h6><span class=\"ez-toc-section\" id=\"Uno_de_sus_estudios_Reasoning_as_a_scientist_ways_of_helping_children_to_use_language_to_learn_science_2003_ha_demostrado_que_los_ninos_que_dominan_la_oratoria_obtienen_mejores_notas_en_matematicas_y_ciencias_Y_es_que_el_discurso_es_crucial_en_las_ciencias_porque_ayuda_a_describir_observaciones_de_forma_clara_razonar_sobre_causas_y_efectos_plantear_preguntas_precisas_formular_hipotesis_analizar_de_forma_critica%E2%80%A6_Tambien_afirman_que_todas_esas_habilidades_brindaran_a_aquellos_que_las_aprendan_el_acceso_a_mejores_puestos_de_trabajo_porque_seran_capaces_de_negociar_sus_condiciones_laborales\"><\/span>Uno de sus estudios (<em>Reasoning as a scientist: ways of helping children to use language to learn science, 2003<\/em>), ha demostrado que <strong><a href=\"https:\/\/www.gaztelueta.com\/es\/innovacion-steam\/hablar-en-publico\" target=\"_blank\" rel=\"noopener noreferrer\">los ni\u00f1os que dominan\u00a0la oratoria<\/a> obtienen mejores notas en matem\u00e1ticas y ciencias.<\/strong> Y es que el discurso es crucial en las ciencias porque ayuda a describir observaciones de forma clara, razonar sobre causas y efectos, plantear preguntas precisas, formular hip\u00f3tesis, analizar de forma cr\u00edtica\u2026 Tambi\u00e9n afirman que todas esas habilidades brindar\u00e1n a aquellos que las aprendan el acceso a mejores puestos de trabajo porque ser\u00e1n capaces de negociar sus condiciones laborales.<span class=\"ez-toc-section-end\"><\/span><\/h6>\n<h6><span class=\"ez-toc-section\" id=\"Su_proyecto_Exploratory_Talks_establece_unas_reglas_para_ensenar_a_los_profesores_a_promover_discusiones_en_el_aula_toda_la_informacion_relevante_se_comparte_todos_los_miembros_del_grupo_estan_invitados_a_contribuir_se_respetan_todas_las_ideas_todos_deben_exponer_de_forma_clara_sus_ideas_o_hay_que_llegar_a_un_acuerdo\"><\/span>Su proyecto <em>Exploratory Talks <\/em>establece unas reglas para ense\u00f1ar a los profesores a promover discusiones en el aula: toda la informaci\u00f3n relevante se comparte, todos los miembros del grupo est\u00e1n invitados a contribuir, se respetan todas las ideas, todos deben exponer de forma clara sus ideas, o hay que llegar a un acuerdo.<span class=\"ez-toc-section-end\"><\/span><\/h6>\n<p><iframe loading=\"lazy\" title=\"AS\u00cd ES una CLASE de HABLAR EN P\u00daBLICO (en Gaztelueta)\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/_11meCWjbQw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<h6><span class=\"ez-toc-section\" id=\"De_esta_forma_los_ninos_con_mas_confianza_en_si_mismos_y_que_suelen_hablar_mas_tiempo_tienen_la_oportunidad_de_escuchar_otros_puntos_de_vista_Los_mas_parados_y_timidos_que_normalmente_se_quedan_callados_y_en_un_segundo_plano_sienten_que_su_contribucion_es_valorada_que_su_voz_vale_tanto_como_la_de_los_demas_Preguntar_al_resto_de_companeros_se_premia_por_parte_del_docente_y_a_la_larga_eso_conduce_a_un_mejor_entendimiento_de_la_postura_de_los_demas_a_una_mayor_empatia\"><\/span>De esta forma, los ni\u00f1os con m\u00e1s confianza en s\u00ed mismos y que suelen hablar m\u00e1s tiempo tienen la oportunidad de escuchar otros puntos de vista. <strong>Los m\u00e1s parados y t\u00edmidos, que normalmente se quedan callados y en un segundo plano, sienten que su contribuci\u00f3n es valorada, que su voz vale tanto como la de los dem\u00e1s.<\/strong> Preguntar al resto de compa\u00f1eros se premia por parte del docente y, a la larga, eso conduce a un mejor entendimiento de la postura de los dem\u00e1s, a una mayor empat\u00eda.<span class=\"ez-toc-section-end\"><\/span><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>En abril de 2018, Ana Torres Men\u00e1rguez entrevistaba en el diario El Pa\u00eds a\u00a0Neil Mercer (Lancashire, 1948), director del Centro de Oratoria de Cambridge. Mercer ha dedicado su carrera a estudiar c\u00f3mo influye la forma de hablar en los resultados acad\u00e9micos, destacaba los beneficios del aprendizaje de la oratoria en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":93,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[90,34,6,79,50],"class_list":["post-92","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion-global","tag-creatividad","tag-hablar-en-publico","tag-motivacion","tag-oratoria","tag-trilinguismo"],"_links":{"self":[{"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/posts\/92"}],"collection":[{"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/comments?post=92"}],"version-history":[{"count":5,"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/posts\/92\/revisions"}],"predecessor-version":[{"id":413,"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/posts\/92\/revisions\/413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/media\/93"}],"wp:attachment":[{"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/media?parent=92"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/categories?post=92"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/tags?post=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}