{"id":585,"date":"2025-11-07T10:17:35","date_gmt":"2025-11-07T08:17:35","guid":{"rendered":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/?p=585"},"modified":"2025-11-07T11:31:22","modified_gmt":"2025-11-07T09:31:22","slug":"educacion-personalizada-2","status":"publish","type":"post","link":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/familias\/educacion-personalizada-2\/","title":{"rendered":"Educaci\u00f3n personalizada: \u00bfmarketing educativo o realidad diferencial?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-flat ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/familias\/educacion-personalizada-2\/#En_los_ultimos_anos_colegios_e_instituciones_educativas_de_todo_tipo_presentan_la_etiqueta_Educacion_personalizada_entre_los_reclamos_de_su_oferta_educativa_La_realidad_sin_embargo_en_la_mayoria_de_los_casos_es_que_los_integrantes_de_la_comunidad_educativa_-padres_alumnos_y_profesores-_caminan_en_paralelo_No_cuentan_con_herramientas_que_unifiquen_y_den_sentido_a_un_proceso_educativo_de_crecimiento_personal_y_academico_orientado_a_la_excelencia\" >En los \u00faltimos a\u00f1os, colegios e instituciones educativas de todo tipo presentan la etiqueta Educaci\u00f3n personalizada entre los reclamos de su oferta educativa. La realidad, sin embargo, en la mayor\u00eda de los casos, es que los integrantes de la comunidad educativa -padres, alumnos y profesores-, caminan en paralelo. No cuentan con herramientas que unifiquen y den sentido a un proceso educativo de crecimiento personal y acad\u00e9mico orientado a la excelencia.<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/familias\/educacion-personalizada-2\/#Las_familias_protagonistas_de_la_educacion\" >Las familias, protagonistas de la educaci\u00f3n<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/familias\/educacion-personalizada-2\/#El_profesorado_modelo_para_la_excelencia_academica_y_personal\" >El profesorado: modelo para la excelencia acad\u00e9mica y personal<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/familias\/educacion-personalizada-2\/#Preceptuacion_y_tutorias_personales_las_piezas_clave_del_proceso\" >Preceptuaci\u00f3n y tutor\u00edas personales: las piezas clave del proceso<\/a><\/li><\/ul><\/nav><\/div>\n<h6><span class=\"ez-toc-section\" id=\"En_los_ultimos_anos_colegios_e_instituciones_educativas_de_todo_tipo_presentan_la_etiqueta_Educacion_personalizada_entre_los_reclamos_de_su_oferta_educativa_La_realidad_sin_embargo_en_la_mayoria_de_los_casos_es_que_los_integrantes_de_la_comunidad_educativa_-padres_alumnos_y_profesores-_caminan_en_paralelo_No_cuentan_con_herramientas_que_unifiquen_y_den_sentido_a_un_proceso_educativo_de_crecimiento_personal_y_academico_orientado_a_la_excelencia\"><\/span>En los \u00faltimos a\u00f1os, colegios e instituciones educativas de todo tipo presentan la etiqueta <i>Educaci\u00f3n personalizada<\/i> entre los reclamos de su oferta educativa. La realidad, sin embargo, en la mayor\u00eda de los casos, es que los integrantes de la comunidad educativa -padres, alumnos y profesores-, caminan en paralelo. No cuentan con herramientas que unifiquen y den sentido a un proceso educativo de crecimiento personal y acad\u00e9mico orientado a la excelencia.<span class=\"ez-toc-section-end\"><\/span><\/h6>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2022\/01\/educacion-personalizada-Gaztelueta-1024x683.jpg\" alt=\"la unidad familia colegio es determinante en la educaci\u00f3n personalizada\" width=\"750\" height=\"500\" class=\"size-large wp-image-1244 aligncenter\" srcset=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2022\/01\/educacion-personalizada-Gaztelueta-1024x683.jpg 1024w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2022\/01\/educacion-personalizada-Gaztelueta-300x200.jpg 300w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2022\/01\/educacion-personalizada-Gaztelueta-768x512.jpg 768w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2022\/01\/educacion-personalizada-Gaztelueta-1536x1024.jpg 1536w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2022\/01\/educacion-personalizada-Gaztelueta-2048x1365.jpg 2048w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2022\/01\/educacion-personalizada-Gaztelueta-360x240.jpg 360w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n\n<p><span style=\"font-weight: 400;\">Los datos avalan que la relaci\u00f3n colegio-familia, con los matices que veremos m\u00e1s adelante, favorece en gran medida el desarrollo integral y potencial de los alumnos abarcando aspectos m\u00e1s all\u00e1 de lo acad\u00e9mico. Un proceso que permite a los j\u00f3venes <\/span><b>descubrir sus talentos y ofrecerlos<\/b><span style=\"font-weight: 400;\"> tanto personal como profesionalmente <strong><a href=\"https:\/\/www.gaztelueta.com\/es\/sociedad\/solidaridad\">en servicio <\/a><\/strong><\/span><a href=\"https:\/\/www.gaztelueta.com\/es\/sociedad\/solidaridad\"><strong>de la sociedad.<\/strong><\/a><\/p>\n<p><span style=\"font-weight: 400;\">\u00bfC\u00f3mo discernir que la etiqueta <\/span><i><span style=\"font-weight: 400;\">Educaci\u00f3n personalizada<\/span><\/i><span style=\"font-weight: 400;\"> de la que hablamos es una realidad y no un eslogan educativo vac\u00edo? <a href=\"https:\/\/www.gaztelueta.com\/es\/admisiones\/por-que-gaztelueta\">La implicaci\u00f3n de las partes en el proyecto educativo personalizado coherente de cada uno de los alumnos<\/a> har\u00e1 viable y real lograrla y en consecuencia <\/span><b>alcanzar m\u00e1ximos de excelencia educativa<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">C\u00f3mo dec\u00eda Garc\u00eda-Hoz, pionero de la educaci\u00f3n personalizada, este modelo educativo busca como finalidad \u00faltima ayudar a hacer efectiva la libertad personal de los estudiantes, incrementando su capacidad para dirigir la propia vida, de modo que \u00e9sta pueda convertirse en un proyecto personal.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Las_familias_protagonistas_de_la_educacion\"><\/span><b>Las familias, protagonistas de la educaci\u00f3n<\/b><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span style=\"font-weight: 400;\">Parece evidente que los que m\u00e1s y mejor conocen a los alumnos son sus padres. Son ellos los que deben perfilar un <\/span><a href=\"https:\/\/www.gaztelueta.com\/es\/nosotros\"><b>proyecto educativo personalizado para cada uno de sus hijos<\/b><\/a><span style=\"font-weight: 400;\">, atendiendo a las caracter\u00edsticas personales de cada uno de ellos. Esto exigir\u00e1 por parte de las familias un <\/span><a href=\"https:\/\/www.youtube.com\/watch?v=NTfwmrY4GDY\" target=\"_blank\" rel=\"noopener\"><b>conocimiento profundo de sus hijos<\/b><\/a><span style=\"font-weight: 400;\"> para, a continuaci\u00f3n, trabajar de forma conjunta con el colegio y sacar as\u00ed el m\u00e1ximo partido a sus fortalezas e ir puliendo con esfuerzo sus puntos de mejora. Adem\u00e1s, profesionales de la educaci\u00f3n orientar\u00e1n a las familias en la labor de conocimiento y definici\u00f3n del proyecto de cada hijo, y dar\u00e1n a los padres herramientas que les ayuden en su labor.\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/03\/abuelos-en-Gaztelueta-index-768x1024.jpg\" alt=\"los abuelos, parte determinante en la sociedad, participan activamente en la vida escolar en Gaztelueta, favoreciendo as\u00ed una relaci\u00f3n familia colegio que da sentido a la educaci\u00f3n personalizada\" width=\"750\" height=\"1000\" class=\"aligncenter wp-image-1112 size-large\" srcset=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/03\/abuelos-en-Gaztelueta-index-768x1024.jpg 768w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/03\/abuelos-en-Gaztelueta-index-225x300.jpg 225w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/03\/abuelos-en-Gaztelueta-index-1152x1536.jpg 1152w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/03\/abuelos-en-Gaztelueta-index-1536x2048.jpg 1536w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/03\/abuelos-en-Gaztelueta-index-scaled.jpg 1920w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Observamos, por otra parte, que la <\/span><b>participaci\u00f3n activa de padres y madres en la vida escolar<\/b><span style=\"font-weight: 400;\"> de sus hijos se traduce irremediablemente en beneficios para \u00e9stos desde la infancia hasta el fin de su formaci\u00f3n. Y es que numerosas investigaciones nos muestran c\u00f3mo la<a href=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/educacion-personalizada\/escuela-de-padres-y-madres\/\"> implicaci\u00f3n parental en la educaci\u00f3n tiene una influencia positiva<\/a>, no s\u00f3lo en su \u00e9xito acad\u00e9mico sino tambi\u00e9n en su desarrollo socioemocional. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">La misma OCDE presenta la implicaci\u00f3n y participaci\u00f3n de los padres como un indicador de esta eficacia y entidades internacionales. Una de ellas es el <\/span><i><span style=\"font-weight: 400;\"><a href=\"https:\/\/globalfrp.org\/Archive\" target=\"_blank\" rel=\"noopener\">Harvard Family Research Project<\/a>,<\/span><\/i><span style=\"font-weight: 400;\"> que refuerza este punto de vista y aportan resultados concluyentes en relaci\u00f3n a la <strong>mejora del rendimiento y del comportamiento de los alumnos en distintos par\u00e1metros como menores tasas de abstenci\u00f3n<\/strong>, menores problemas de disciplina en las aulas o el aumento del rendimiento acad\u00e9mico, entre otros.\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/01\/formacion-de-familias-1-1024x768.jpeg\" alt=\"las familias de Gaztelueta encuentran en gaztelueta, una extensi\u00f3n de su unidad familiar, lo que sin duda es determinante en la educaci\u00f3n personalizada\" width=\"750\" height=\"563\" class=\"aligncenter wp-image-1044 size-large\" srcset=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/01\/formacion-de-familias-1-1024x768.jpeg 1024w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/01\/formacion-de-familias-1-300x225.jpeg 300w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/01\/formacion-de-familias-1-768x576.jpeg 768w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/01\/formacion-de-familias-1-1536x1152.jpeg 1536w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/01\/formacion-de-familias-1-2048x1536.jpeg 2048w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Sacar el mayor partido a los medios que el colegio propone de forma natural y progresiva a lo largo de los a\u00f1os de escolarizaci\u00f3n de los hijos, depender\u00e1 de cada familia,<strong> teniendo la posibilidad de vivir la etapa escolar en primera persona con los beneficios que trae consigo y convirtiendo el colegio de sus hijos en un <\/strong><\/span><strong><i>colegio de familias<\/i><\/strong><span style=\"font-weight: 400;\"> en el que tanto alumnos como padres disfruten de un proceso de crecimiento personal y familiar.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h4><b><a href=\"https:\/\/www.youtube.com\/playlist?list=PLMuwP7__vNvO02QP0g4H9AiCq77avcnd8\" target=\"_blank\" rel=\"noopener\">El profesorado<\/a>: modelo para la excelencia acad\u00e9mica y personal<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Los papeles del profesorado, el tutor de cada alumno y su preceptor ser\u00e1n a su vez determinantes. Ser\u00e1 labor del equipo docente, liderado por las figuras de tutores y preceptores, observar y poner los medios necesarios para el conocimiento global de sus alumnos. El \u201cyo alumno\u201d de cada uno de ellos aportar\u00e1 cierta informaci\u00f3n que tendr\u00e1 poco o ning\u00fan valor sin la asociada a su \u201cyo amigo\u201d, \u201cyo hermano\u201d, \u201cyo integrante de un equipo\u201d, etc.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.gaztelueta.com\/es\/por-que-gaztelueta\">Un equipo docente implicado ser\u00e1 por tanto determinante<\/a>; un equipo de profesorado que observa el proceso, recoge informaci\u00f3n, la analiza y la utiliza en beneficio de cada alumno,\u00a0 en comunicaci\u00f3n regular y fluida y empe\u00f1ado en buscar el crecimiento constante de sus pupilos y por encima de todo una<\/span><b> relaci\u00f3n profesor-alumno basada en el respeto y la confianza mutua.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Y en paralelo, una <\/span><b>comunicaci\u00f3n con las familias<\/b><span style=\"font-weight: 400;\"> en la que, con el conocimiento de las partes, conseguir la mejor versi\u00f3n de cada uno de nuestros alumnos.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/11\/educacion-personalizada-Gaztelueta-aula-1024x683.jpg\" alt=\"la observaci\u00f3n y la atenci\u00f3n individualizada de cada uno de nuestros alumnos permite una verdadera educaci\u00f3n personalizada\" width=\"750\" height=\"500\" class=\"size-large wp-image-1246 aligncenter\" srcset=\"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/11\/educacion-personalizada-Gaztelueta-aula-1024x683.jpg 1024w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/11\/educacion-personalizada-Gaztelueta-aula-300x200.jpg 300w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/11\/educacion-personalizada-Gaztelueta-aula-768x512.jpg 768w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/11\/educacion-personalizada-Gaztelueta-aula-1536x1024.jpg 1536w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/11\/educacion-personalizada-Gaztelueta-aula-2048x1365.jpg 2048w, https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-content\/uploads\/2025\/11\/educacion-personalizada-Gaztelueta-aula-360x240.jpg 360w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Preceptuacion_y_tutorias_personales_las_piezas_clave_del_proceso\"><\/span><b>Preceptuaci\u00f3n y tutor\u00edas personales: las piezas clave del proceso<\/b><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span style=\"font-weight: 400;\">La comunicaci\u00f3n y relaci\u00f3n de padres, profesores y alumnos se materializa entre otros, en los ejercicios de <\/span><b>preceptuaci\u00f3n<\/b><span style=\"font-weight: 400;\"> (alumno-profesor) y <\/span><b>tutor\u00eda<\/b> <span style=\"font-weight: 400;\">(padres-profesor), ejes fundamentales del proyecto educativo de Gaztelueta.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las reuniones peri\u00f3dicas con los padres de cada alumno ayudar\u00e1n a definir y concretar su proyecto, definiendo objetivos y salvando los obst\u00e1culos que se encuentren en el camino. Ser\u00e1 en estas reuniones en las que todo lo anterior tomar\u00e1 forma y el esfuerzo de todas las partes vea progresivamente sus frutos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Todas las partes de la <\/span><b>comunidad educativa<\/b><span style=\"font-weight: 400;\">, participando de forma activa y <\/span><b>comprometida en un ejercicio coherente<\/b><span style=\"font-weight: 400;\"> con un objetivo \u00fanico: formar, adem\u00e1s de profesionales competentes, personas libres e \u00edntegras, aut\u00f3nomas y solidarias. Y juntos es m\u00e1s f\u00e1cil.<\/span><\/p>\n<p><iframe loading=\"lazy\" title=\"\u00bfC\u00f3mo te imaginas el futuro de tus hijos?\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/GAWD8HUlif0?start=2&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los \u00faltimos a\u00f1os, colegios e instituciones educativas de todo tipo presentan la etiqueta Educaci\u00f3n personalizada entre los reclamos de su oferta educativa. La realidad, sin embargo, en la mayor\u00eda de los casos, es que los integrantes de la comunidad educativa -padres, alumnos y profesores-, caminan en paralelo. No cuentan [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1246,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[288],"tags":[17,219,61,113,87],"class_list":["post-585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-familias","tag-educacion-personalizada","tag-excelencia-academica","tag-familia","tag-orientacion-familiar","tag-preceptuacion"],"_links":{"self":[{"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/posts\/585"}],"collection":[{"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/comments?post=585"}],"version-history":[{"count":5,"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/posts\/585\/revisions"}],"predecessor-version":[{"id":1247,"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/posts\/585\/revisions\/1247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/media\/1246"}],"wp:attachment":[{"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/media?parent=585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/categories?post=585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gaztelueta.com\/lapasiondeeducar\/wp-json\/wp\/v2\/tags?post=585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}